{"id":12842,"date":"2020-03-11T10:00:36","date_gmt":"2020-03-11T13:00:36","guid":{"rendered":"https:\/\/graduacaofia.wpenginepowered.com\/?p=12842"},"modified":"2020-03-11T10:00:36","modified_gmt":"2020-03-11T13:00:36","slug":"apresentacao-de-trabalho","status":"publish","type":"post","link":"https:\/\/fia.com.br\/graduacao\/blog\/apresentacao-de-trabalho\/","title":{"rendered":"Apresenta\u00e7\u00e3o de trabalho: dicas para ter sucesso"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Seja voc\u00ea um estudante ou um profissional no mercado,\nrealizar uma boa apresenta\u00e7\u00e3o de trabalho \u00e9 fundamental para alcan\u00e7ar seus\nobjetivos. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Expor seus resultados, explicar o projeto que voc\u00ea est\u00e1 inserido, demonstrar o seu trabalho de pesquisa e desenvolvimento, tudo isso pode requerer apresenta\u00e7\u00f5es para professores, colegas e gestores. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mas mesmo sendo algo natural e comum, a apresenta\u00e7\u00e3o de\ntrabalhos inspira sentimentos n\u00e3o muito positivos em v\u00e1rias pessoas.\nNervosismo, gagueira, brancos. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m \u00e9 comum erros b\u00e1sicos como apresenta\u00e7\u00e3o de slides tediosas, perguntas que n\u00e3o encontram respostas e desencontro de ideias, especialmente quando o trabalho \u00e9 em grupo. Para solucionar essas quest\u00f5es vamos citar uma s\u00e9rie de dicas para ajudar na sua apresenta\u00e7\u00e3o de trabalho, seja na sala de aula ou na sala de reuni\u00f5es da empresa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"> N\u00e3o deixe a apresenta\u00e7\u00e3o de trabalho para a \u00faltima hora<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea ver\u00e1 que a maioria dos erros aqui s\u00e3o coisas comuns e\nque se repetem. Uma delas \u00e9 deixar a produ\u00e7\u00e3o da apresenta\u00e7\u00e3o para a \u00faltima\nhora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O <a href=\"https:\/\/medium.com\/@HeathEvans\/content-is-king-essay-by-bill-gates-1996-df74552f80d9\">conte\u00fado\n\u00e9 Rei<\/a>, sem d\u00favidas, ent\u00e3o a pesquisa, a elabora\u00e7\u00e3o da tese, tudo isso precisa\nter destaque. Mas a apresenta\u00e7\u00e3o desse conte\u00fado \u00e9 algo de vital import\u00e2ncia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fica claro quando a apresenta\u00e7\u00e3o foi feita de \u00faltima hora.\nSlides que n\u00e3o conversam um com o outro, pessoas atropelando ideias e que\nexp\u00f5em os mesmos argumentos, at\u00e9 a escolha de layout que \u00e9 duvidosa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea n\u00e3o pode dedicar muito tempo \u00e0 parte visual, escolha\nalgo b\u00e1sico: fundo branco com letras pretas e detalhes em vermelho. Assim \u00e9\nposs\u00edvel ler facilmente e hierarquizar as informa\u00e7\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se a apresenta\u00e7\u00e3o de trabalho for em grupo, converse sobre o\nque cada um falar\u00e1, sem um contradizer o outro ou repetir as mesmas falas. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O mais importante de uma apresenta\u00e7\u00e3o \u00e9 <a href=\"https:\/\/fia.com.br\/blog\/storytelling\/\">estabelecer uma narrativa<\/a>. Com\nin\u00edcio, meio e fim e coesa. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Abra espa\u00e7o para d\u00favidas e discuss\u00f5es entre os presentes, mas n\u00e3o para questionamentos sobre a validade do trabalho ou sua apura\u00e7\u00e3o de dados.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"> Pense no seu p\u00fablico<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Um bom orador n\u00e3o \u00e9 o s\u00f3 o que fala bem, mas o que consegue\natingir as mais diversas pessoas. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00e3o \u00e9 \u00e0 toa que os grandes oradores podem falar para\nmultid\u00f5es ou se destacar em uma sala, tocar pessoas de diferentes forma\u00e7\u00f5es\neducacionais e <a href=\"https:\/\/pt.wikipedia.org\/wiki\/Estratifica%C3%A7%C3%A3o_social\">estratos\nsociais<\/a>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Isso se d\u00e1 pelo fato que um bom orador conhece o seu p\u00fablico\ne se conecta com ele. Tenha isso em mente ao fazer uma apresenta\u00e7\u00e3o de\ntrabalho. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vamos imaginar que voc\u00ea est\u00e1 trabalhando em um projeto de\nimplementa\u00e7\u00e3o de um software, que ir\u00e1 automatizar diversos processos na sua\nempresa. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se a sua apresenta\u00e7\u00e3o ser\u00e1 para os colaboradores, que ter\u00e3o\nhoras de trabalho poupadas, mas ainda assim v\u00e3o ter que aprender a como mexer\nno software, o seu tom precisa ser informativo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como o software funciona, como ele \u00e9 usado, porque ele\nprecisa ser usado e por que ele ser\u00e1 positivo para os colaboradores s\u00e3o\nperguntas que voc\u00ea precisa responder.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mas e se a apresenta\u00e7\u00e3o fosse para os gestores e l\u00edderes da\nsua empresa, que n\u00e3o ir\u00e3o usar o software, mas precisam aprovar a ideia?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Explicar sua import\u00e2ncia \u00e9 vital, mas o foco aqui precisa\nser nos recursos que ser\u00e3o poupados: o menor tempo gasto, a menor necessidade\nde pessoal para essa tarefa e o porqu\u00ea do custo de implementa\u00e7\u00e3o valer a pena.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seja polivalente com sua mensagem porque assim ela ter\u00e1\nverdadeira resson\u00e2ncia. E sua apresenta\u00e7\u00e3o de trabalho ser\u00e1 efetiva.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Treine a sua mensagem<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Independentemente de sua apresenta\u00e7\u00e3o de trabalho ser\nsolit\u00e1ria ou em grupo, n\u00e3o deixe de pelo menos praticar ela uma vez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">V\u00e1 ponto por ponto, testando n\u00e3o s\u00f3 suas falas, mas\nposs\u00edveis incongru\u00eancias e pontos que n\u00e3o est\u00e3o bem explicados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Treine na frente do espelho ou at\u00e9 se filmando com o celular.\nAssim voc\u00ea poder\u00e1 ver a apresenta\u00e7\u00e3o depois e notar sua linguagem corporal ou <a href=\"https:\/\/mundoeducacao.bol.uol.com.br\/gramatica\/vicios-linguagem.htm\">v\u00edcios\nde linguagem<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Caso a apresenta\u00e7\u00e3o de trabalho seja em grupo, separe um\ntempo, nem que seja perto do momento da exposi\u00e7\u00e3o, para fazer esse treinamento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00e3o h\u00e1 nada pior do que ver uma apresenta\u00e7\u00e3o em grupo onde\nas pessoas se atropelam e falam as mesmas coisas repetidas vezes. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E \u00e9 isso que acontece quando se improvisa: os brancos s\u00e3o\nconstantes e o natural \u00e9 voltar ao ponto de partida. Assim a linha narrativa\nn\u00e3o se desenvolve.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Crie esse roteiro, com come\u00e7o, meio e fim e teste ele. Essa\n\u00e9 a melhor forma de fazer uma apresenta\u00e7\u00e3o de trabalho cativante.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Tente ser natural<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O est\u00e1gio final de um bom apresentador ou <a href=\"https:\/\/fia.com.br\/blog\/oratoria\/\">orador<\/a> \u00e9 ter completa naturalidade\nao falar em p\u00fablico. Isso n\u00e3o \u00e9 algo f\u00e1cil de ser atingido e certas pessoas t\u00eam\nmais facilidade que outras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pr\u00e1tica ajuda muito a conquistar essa naturalidade.\nConhecer o tema a fundo tamb\u00e9m. Por isso, mesmo que voc\u00ea parta realmente do\nzero na quest\u00e3o de \u201cvender seu peixe\u201d, n\u00e3o poupe no treinamento e no\nconhecimento da informa\u00e7\u00e3o que ser\u00e1 compartilhada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A partir disso, tente: <\/p>\n\n\n\n<ul class=\"flat-list style1 wp-block-list\"><li>Gesticular e movimentar-se: ficar parado como uma est\u00e1tua demonstra certo nervosismo. Andar, abrir os bra\u00e7os, mudar o tom da voz quebra a monotonia e d\u00e1 mais for\u00e7a \u00e0 sua mensagem;<\/li><li>Focar uma pessoa: se a ideia de falar para muitas pessoas te deixa nervoso (a), foque em uma pessoa da plateia, seja ela conhecida ou n\u00e3o;<\/li><li>Estabelecer uma conversa: com certeza voc\u00ea ser\u00e1 a pessoa que falar\u00e1 mais, mas crie uma conversa, com uma sauda\u00e7\u00e3o, uma mensagem de despedida, abra a possibilidade para perguntas.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">O <a href=\"https:\/\/fia.com.br\/blog\/tecnicas-de-apresentacao\/\">blog\nda FIA<\/a> criou um texto com v\u00e1rias t\u00e9cnicas que podem ser usadas. D\u00ea uma\nconferida e use-as sem modera\u00e7\u00e3o. Ache a sua forma, o seu jeito e isso far\u00e1 com\nque o processo seja natural e mais efetivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E boa sorte na sua pr\u00f3xima apresenta\u00e7\u00e3o de trabalho!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seja voc\u00ea um estudante ou um profissional no mercado, realizar uma boa apresenta\u00e7\u00e3o de trabalho \u00e9 fundamental para alcan\u00e7ar seus objetivos. Expor seus resultados, explicar o projeto que voc\u00ea est\u00e1 inserido, demonstrar o seu trabalho de pesquisa e desenvolvimento, tudo isso pode requerer apresenta\u00e7\u00f5es para professores, colegas e gestores. Mas mesmo sendo algo natural e [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":12857,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-12842","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Apresenta\u00e7\u00e3o de trabalho: dicas para ter sucesso - Gradua\u00e7\u00e3o<\/title>\n<meta name=\"description\" content=\"Seja voc\u00ea um estudante ou um profissional no mercado, realizar uma boa apresenta\u00e7\u00e3o de trabalho \u00e9 fundamental para alcan\u00e7ar seus objetivos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fia.com.br\/graduacao\/blog\/apresentacao-de-trabalho\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apresenta\u00e7\u00e3o de trabalho: dicas para ter sucesso - Gradua\u00e7\u00e3o\" \/>\n<meta property=\"og:description\" content=\"Seja voc\u00ea um estudante ou um profissional no mercado, realizar uma boa apresenta\u00e7\u00e3o de trabalho \u00e9 fundamental para alcan\u00e7ar seus objetivos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fia.com.br\/graduacao\/blog\/apresentacao-de-trabalho\/\" \/>\n<meta property=\"og:site_name\" content=\"Gradua\u00e7\u00e3o\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-11T13:00:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fia.com.br\/graduacao\/wp-content\/uploads\/sites\/6\/2020\/03\/iStock-1141509021-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"FIA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"FIA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fia.com.br\/graduacao\/blog\/apresentacao-de-trabalho\/\",\"url\":\"https:\/\/fia.com.br\/graduacao\/blog\/apresentacao-de-trabalho\/\",\"name\":\"Apresenta\u00e7\u00e3o de trabalho: dicas para ter sucesso - Gradua\u00e7\u00e3o\",\"isPartOf\":{\"@id\":\"https:\/\/fia.com.br\/graduacao\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/fia.com.br\/graduacao\/blog\/apresentacao-de-trabalho\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/fia.com.br\/graduacao\/blog\/apresentacao-de-trabalho\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/fia.com.br\/graduacao\/wp-content\/uploads\/sites\/6\/2020\/03\/iStock-1141509021-scaled.jpg\",\"datePublished\":\"2020-03-11T13:00:36+00:00\",\"dateModified\":\"2020-03-11T13:00:36+00:00\",\"author\":{\"@id\":\"https:\/\/fia.com.br\/graduacao\/#\/schema\/person\/09d96b732802edb5307e35f3aca6f31b\"},\"description\":\"Seja voc\u00ea um estudante ou um profissional no mercado, realizar uma boa apresenta\u00e7\u00e3o de trabalho \u00e9 fundamental para alcan\u00e7ar seus objetivos.\",\"breadcrumb\":{\"@id\":\"https:\/\/fia.com.br\/graduacao\/blog\/apresentacao-de-trabalho\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fia.com.br\/graduacao\/blog\/apresentacao-de-trabalho\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/fia.com.br\/graduacao\/blog\/apresentacao-de-trabalho\/#primaryimage\",\"url\":\"https:\/\/fia.com.br\/graduacao\/wp-content\/uploads\/sites\/6\/2020\/03\/iStock-1141509021-scaled.jpg\",\"contentUrl\":\"https:\/\/fia.com.br\/graduacao\/wp-content\/uploads\/sites\/6\/2020\/03\/iStock-1141509021-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Apresenta\u00e7\u00e3o de Trabalho\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fia.com.br\/graduacao\/blog\/apresentacao-de-trabalho\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/fia.com.br\/graduacao\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apresenta\u00e7\u00e3o de trabalho: dicas para ter sucesso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fia.com.br\/graduacao\/#website\",\"url\":\"https:\/\/fia.com.br\/graduacao\/\",\"name\":\"FIA\",\"description\":\"FIA - Funda\u00e7\u00e3o Instituto de Administra\u00e7\u00e3o\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fia.com.br\/graduacao\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/fia.com.br\/graduacao\/#\/schema\/person\/09d96b732802edb5307e35f3aca6f31b\",\"name\":\"FIA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/fia.com.br\/graduacao\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b51150cc482a9fcb93d232c2a66e1f1c4dd3300ea21b8e732bfb1a73f707b6de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b51150cc482a9fcb93d232c2a66e1f1c4dd3300ea21b8e732bfb1a73f707b6de?s=96&d=mm&r=g\",\"caption\":\"FIA\"},\"description\":\"Com um olhar sempre no futuro, desenvolvemos e disseminamos conhecimentos de teorias e m\u00e9todos de Administra\u00e7\u00e3o de Empresas, aperfei\u00e7oando o desempenho das institui\u00e7\u00f5es brasileiras atrav\u00e9s de tr\u00eas linhas b\u00e1sicas de atividade: Educa\u00e7\u00e3o Executiva, Pesquisa e Consultoria.\",\"url\":\"https:\/\/fia.com.br\/graduacao\/blog\/author\/fia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apresenta\u00e7\u00e3o de trabalho: dicas para ter sucesso - Gradua\u00e7\u00e3o","description":"Seja voc\u00ea um estudante ou um profissional no mercado, realizar uma boa apresenta\u00e7\u00e3o de trabalho \u00e9 fundamental para alcan\u00e7ar seus objetivos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fia.com.br\/graduacao\/blog\/apresentacao-de-trabalho\/","og_locale":"pt_BR","og_type":"article","og_title":"Apresenta\u00e7\u00e3o de trabalho: dicas para ter sucesso - Gradua\u00e7\u00e3o","og_description":"Seja voc\u00ea um estudante ou um profissional no mercado, realizar uma boa apresenta\u00e7\u00e3o de trabalho \u00e9 fundamental para alcan\u00e7ar seus objetivos.","og_url":"https:\/\/fia.com.br\/graduacao\/blog\/apresentacao-de-trabalho\/","og_site_name":"Gradua\u00e7\u00e3o","article_published_time":"2020-03-11T13:00:36+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/fia.com.br\/graduacao\/wp-content\/uploads\/sites\/6\/2020\/03\/iStock-1141509021-scaled.jpg","type":"image\/jpeg"}],"author":"FIA","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"FIA","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fia.com.br\/graduacao\/blog\/apresentacao-de-trabalho\/","url":"https:\/\/fia.com.br\/graduacao\/blog\/apresentacao-de-trabalho\/","name":"Apresenta\u00e7\u00e3o de trabalho: dicas para ter sucesso - Gradua\u00e7\u00e3o","isPartOf":{"@id":"https:\/\/fia.com.br\/graduacao\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fia.com.br\/graduacao\/blog\/apresentacao-de-trabalho\/#primaryimage"},"image":{"@id":"https:\/\/fia.com.br\/graduacao\/blog\/apresentacao-de-trabalho\/#primaryimage"},"thumbnailUrl":"https:\/\/fia.com.br\/graduacao\/wp-content\/uploads\/sites\/6\/2020\/03\/iStock-1141509021-scaled.jpg","datePublished":"2020-03-11T13:00:36+00:00","dateModified":"2020-03-11T13:00:36+00:00","author":{"@id":"https:\/\/fia.com.br\/graduacao\/#\/schema\/person\/09d96b732802edb5307e35f3aca6f31b"},"description":"Seja voc\u00ea um estudante ou um profissional no mercado, realizar uma boa apresenta\u00e7\u00e3o de trabalho \u00e9 fundamental para alcan\u00e7ar seus objetivos.","breadcrumb":{"@id":"https:\/\/fia.com.br\/graduacao\/blog\/apresentacao-de-trabalho\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fia.com.br\/graduacao\/blog\/apresentacao-de-trabalho\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/fia.com.br\/graduacao\/blog\/apresentacao-de-trabalho\/#primaryimage","url":"https:\/\/fia.com.br\/graduacao\/wp-content\/uploads\/sites\/6\/2020\/03\/iStock-1141509021-scaled.jpg","contentUrl":"https:\/\/fia.com.br\/graduacao\/wp-content\/uploads\/sites\/6\/2020\/03\/iStock-1141509021-scaled.jpg","width":2560,"height":1707,"caption":"Apresenta\u00e7\u00e3o de Trabalho"},{"@type":"BreadcrumbList","@id":"https:\/\/fia.com.br\/graduacao\/blog\/apresentacao-de-trabalho\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/fia.com.br\/graduacao\/"},{"@type":"ListItem","position":2,"name":"Apresenta\u00e7\u00e3o de trabalho: dicas para ter sucesso"}]},{"@type":"WebSite","@id":"https:\/\/fia.com.br\/graduacao\/#website","url":"https:\/\/fia.com.br\/graduacao\/","name":"FIA","description":"FIA - Funda\u00e7\u00e3o Instituto de Administra\u00e7\u00e3o","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fia.com.br\/graduacao\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/fia.com.br\/graduacao\/#\/schema\/person\/09d96b732802edb5307e35f3aca6f31b","name":"FIA","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/fia.com.br\/graduacao\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b51150cc482a9fcb93d232c2a66e1f1c4dd3300ea21b8e732bfb1a73f707b6de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b51150cc482a9fcb93d232c2a66e1f1c4dd3300ea21b8e732bfb1a73f707b6de?s=96&d=mm&r=g","caption":"FIA"},"description":"Com um olhar sempre no futuro, desenvolvemos e disseminamos conhecimentos de teorias e m\u00e9todos de Administra\u00e7\u00e3o de Empresas, aperfei\u00e7oando o desempenho das institui\u00e7\u00f5es brasileiras atrav\u00e9s de tr\u00eas linhas b\u00e1sicas de atividade: Educa\u00e7\u00e3o Executiva, Pesquisa e Consultoria.","url":"https:\/\/fia.com.br\/graduacao\/blog\/author\/fia\/"}]}},"_links":{"self":[{"href":"https:\/\/fia.com.br\/graduacao\/wp-json\/wp\/v2\/posts\/12842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fia.com.br\/graduacao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fia.com.br\/graduacao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fia.com.br\/graduacao\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/fia.com.br\/graduacao\/wp-json\/wp\/v2\/comments?post=12842"}],"version-history":[{"count":0,"href":"https:\/\/fia.com.br\/graduacao\/wp-json\/wp\/v2\/posts\/12842\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fia.com.br\/graduacao\/wp-json\/wp\/v2\/media\/12857"}],"wp:attachment":[{"href":"https:\/\/fia.com.br\/graduacao\/wp-json\/wp\/v2\/media?parent=12842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fia.com.br\/graduacao\/wp-json\/wp\/v2\/categories?post=12842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fia.com.br\/graduacao\/wp-json\/wp\/v2\/tags?post=12842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}